{"id":32946,"date":"2022-08-28T00:01:25","date_gmt":"2022-08-27T17:01:25","guid":{"rendered":"https:\/\/pwschool.ac.th\/?p=32946"},"modified":"2022-08-28T00:16:36","modified_gmt":"2022-08-27T17:16:36","slug":"%e0%b8%84%e0%b9%88%e0%b8%b2%e0%b8%a2%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8-foreign-languages-camp-2022-%e0%b8%8a","status":"publish","type":"post","link":"https:\/\/pwschool.ac.th\/home\/archives\/32946","title":{"rendered":"\u0e04\u0e48\u0e32\u0e22\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 Foreign Languages Camp 2022 \u0e0a\u0e31\u0e49\u0e19 \u0e21.4-6 \u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 1 \u0e1b\u0e35 2565"},"content":{"rendered":"\n<p class=\"has-text-align-center\">\u0e04\u0e48\u0e32\u0e22\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 Foreign Languages Camp 2022 \u0e0a\u0e31\u0e49\u0e19 \u0e21.4-6 \u0e20\u0e32\u0e04\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 1 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2565\u200b <\/p>\n\n\n\n<p class=\"has-text-align-center\">\u0e27\u0e31\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c\u0e17\u0e35\u0e48\u200b 27\u200b \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21\u200b 2565<\/p>\n\n\n\n<p class=\"has-text-align-center\">\u200b\u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e21\u0e07\u0e04\u0e25\u0e27\u0e38\u0e12\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u200b \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333-1024x682.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333-1024x682.jpg\" alt=\"\" data-id=\"32947\" data-link=\"https:\/\/pwschool.ac.th\/?attachment_id=32947\" class=\"wp-image-32947\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333-768x511.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618975333.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270-1024x682.jpg\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270-1024x682.jpg\" alt=\"\" data-id=\"32948\" data-link=\"https:\/\/pwschool.ac.th\/?attachment_id=32948\" class=\"wp-image-32948\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270-768x511.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618977270.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333-1024x682.jpg\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333-1024x682.jpg\" alt=\"\" data-id=\"32949\" data-link=\"https:\/\/pwschool.ac.th\/?attachment_id=32949\" class=\"wp-image-32949\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333-768x511.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661618979333.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386-1024x682.jpg\" alt=\"\" data-id=\"32951\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619519386\" class=\"wp-image-32951\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619519386.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078-1024x682.jpg\" alt=\"\" data-id=\"32952\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619533078\" class=\"wp-image-32952\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619533078.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163-1024x682.jpg\" alt=\"\" data-id=\"32953\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619543163\" class=\"wp-image-32953\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619543163.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009-1024x682.jpg\" alt=\"\" data-id=\"32954\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619547009\" class=\"wp-image-32954\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619547009.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209-1024x682.jpg\" alt=\"\" data-id=\"32955\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619551209\" class=\"wp-image-32955\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619551209.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983-1024x682.jpg\" alt=\"\" data-id=\"32957\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619553983\" class=\"wp-image-32957\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619553983.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464-1024x682.jpg\" alt=\"\" data-id=\"32958\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619559464\" class=\"wp-image-32958\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619559464.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585-1024x682.jpg\" alt=\"\" data-id=\"32959\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619569585\" class=\"wp-image-32959\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619569585.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794-1024x682.jpg\" alt=\"\" data-id=\"32960\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619573794\" class=\"wp-image-32960\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619573794.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216-1024x682.jpg\" alt=\"\" data-id=\"32961\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619579216\" class=\"wp-image-32961\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619579216.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503-1024x682.jpg\" alt=\"\" data-id=\"32962\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619585503\" class=\"wp-image-32962\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619585503.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316-1024x682.jpg\" alt=\"\" data-id=\"32963\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619593316\" class=\"wp-image-32963\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619593316.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680-1024x682.jpg\" alt=\"\" data-id=\"32964\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619597680\" class=\"wp-image-32964\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619597680.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575-1024x682.jpg\" alt=\"\" data-id=\"32965\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619605575\" class=\"wp-image-32965\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619605575.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559-1024x682.jpg\" alt=\"\" data-id=\"32966\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619609559\" class=\"wp-image-32966\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619609559.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856-1024x682.jpg\" alt=\"\" data-id=\"32967\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619612856\" class=\"wp-image-32967\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619612856.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286-1024x682.jpg\" alt=\"\" data-id=\"32968\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619615286\" class=\"wp-image-32968\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619615286.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088-1024x682.jpg\" alt=\"\" data-id=\"32969\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619618088\" class=\"wp-image-32969\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619618088.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359-1024x682.jpg\" alt=\"\" data-id=\"32970\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619620359\" class=\"wp-image-32970\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619620359.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861-1024x682.jpg\" alt=\"\" data-id=\"32971\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619622861\" class=\"wp-image-32971\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619622861.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324-1024x682.jpg\" alt=\"\" data-id=\"32972\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619625324\" class=\"wp-image-32972\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619625324.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655-1024x682.jpg\" alt=\"\" data-id=\"32973\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619628655\" class=\"wp-image-32973\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619628655.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472-1024x682.jpg\" alt=\"\" data-id=\"32974\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619632472\" class=\"wp-image-32974\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619632472.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524-1024x682.jpg\" alt=\"\" data-id=\"32975\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619635524\" class=\"wp-image-32975\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619635524.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132-1024x682.jpg\" alt=\"\" data-id=\"32976\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619638132\" class=\"wp-image-32976\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492-1024x682.jpg\" alt=\"\" data-id=\"32977\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619653492\" class=\"wp-image-32977\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619653492.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222-1024x682.jpg\" alt=\"\" data-id=\"32978\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619662222\" class=\"wp-image-32978\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619662222.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772-1024x682.jpg\" alt=\"\" data-id=\"32979\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619673772\" class=\"wp-image-32979\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619673772.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176-1024x682.jpg\" alt=\"\" data-id=\"32980\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619678176\" class=\"wp-image-32980\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619678176.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213-1024x682.jpg\" alt=\"\" data-id=\"32981\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619681213\" class=\"wp-image-32981\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619681213.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504-1024x682.jpg\" alt=\"\" data-id=\"32982\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619683504\" class=\"wp-image-32982\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619683504.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055-1024x682.jpg\" alt=\"\" data-id=\"32983\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619692055\" class=\"wp-image-32983\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619692055.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534-1024x682.jpg\" alt=\"\" data-id=\"32984\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619696534\" class=\"wp-image-32984\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619696534.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025-1024x682.jpg\" alt=\"\" data-id=\"32985\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619699025\" class=\"wp-image-32985\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619699025.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582-1024x682.jpg\" alt=\"\" data-id=\"32986\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619703582\" class=\"wp-image-32986\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619703582.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081-1024x682.jpg\" alt=\"\" data-id=\"32987\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/32946\/fb_img_1661619710081\" class=\"wp-image-32987\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081-1024x682.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081-300x200.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081-768x512.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619710081.jpg 1081w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/241016499264147\/posts\/pfbid06iTVHQPeAZDDkPGs1pu3xntsWL7gVLXnFfAT2NxLCP7Uu7VqtVHnQF1jnm1eCHcDl\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e48\u0e32\u0e22\u0e20\u0e32\u0e29\u0e32\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 Foreign Languages Camp 2022 \u0e0a\u0e31\u0e49\u0e19 \u0e21.4 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-32946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6"],"jetpack_featured_media_url":"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/08\/FB_IMG_1661619638132.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/32946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/comments?post=32946"}],"version-history":[{"count":2,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/32946\/revisions"}],"predecessor-version":[{"id":32988,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/32946\/revisions\/32988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/media\/32976"}],"wp:attachment":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/media?parent=32946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/categories?post=32946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/tags?post=32946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}