{"id":33869,"date":"2022-10-11T16:29:09","date_gmt":"2022-10-11T09:29:09","guid":{"rendered":"https:\/\/pwschool.ac.th\/?p=33869"},"modified":"2022-10-13T09:45:28","modified_gmt":"2022-10-13T02:45:28","slug":"%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%87%e0%b8%b2%e0%b8%99%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%9e%e0%b8%93%e0%b8%b5%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%9a%e0%b8%b1%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/pwschool.ac.th\/home\/archives\/33869","title":{"rendered":"\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565"},"content":{"rendered":"\n<p class=\"has-text-align-center\">\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565<br>\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e32\u0e27\u0e19\u0e32 \u0e2d\u0e1a\u0e15.\u0e1a\u0e32\u0e07\u0e42\u0e09\u0e25\u0e07<br>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 4-9 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 2565<br>\u0e13 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445-1024x768.jpg\" alt=\"\" data-id=\"33878\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/attachment\/1665478890445\" class=\"wp-image-33878\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/1665478890445.jpg 1478w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286-1024x768.jpg\" alt=\"\" data-id=\"33879\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565280573402286\" class=\"wp-image-33879\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565280573402286.jpg 1478w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640.jpg\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640-1024x768.jpg\" alt=\"\" data-id=\"33880\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565284332948640\" class=\"wp-image-33880\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565284332948640.jpg 1478w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597-1024x768.jpg\" alt=\"\" data-id=\"33881\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565291016322597\" class=\"wp-image-33881\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565291016322597.jpg 1478w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533-1024x768.jpg\" alt=\"\" data-id=\"33882\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565298802058533\" class=\"wp-image-33882\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565298802058533.jpg 1479w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053-1024x768.jpg\" alt=\"\" data-id=\"33883\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565309554984053\" class=\"wp-image-33883\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565309554984053.jpg 1479w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281-1024x768.jpg\" alt=\"\" data-id=\"33884\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565314414177281\" class=\"wp-image-33884\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565314414177281.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072-1024x768.jpg\" alt=\"\" data-id=\"33885\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565317487597072\" class=\"wp-image-33885\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565317487597072.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800-1024x768.jpg\" alt=\"\" data-id=\"33886\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565326044177800\" class=\"wp-image-33886\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565326044177800.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549-1024x768.jpg\" alt=\"\" data-id=\"33887\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565335204546549\" class=\"wp-image-33887\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565335204546549.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130-1024x768.jpg\" alt=\"\" data-id=\"33888\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565347758761130\" class=\"wp-image-33888\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565347758761130.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128-1024x768.jpg\" alt=\"\" data-id=\"33889\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/line_565360046311128\" class=\"wp-image-33889\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/line_565360046311128.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934.jpg\" alt=\"\" data-id=\"33890\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479167934\" class=\"wp-image-33890\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479167934-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133.jpg\" alt=\"\" data-id=\"33891\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479170133\" class=\"wp-image-33891\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479170133-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711.jpg\" alt=\"\" data-id=\"33892\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479173711\" class=\"wp-image-33892\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479173711-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292.jpg\" alt=\"\" data-id=\"33893\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479176292\" class=\"wp-image-33893\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479176292-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848.jpg\" alt=\"\" data-id=\"33894\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479178848\" class=\"wp-image-33894\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479178848-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045.jpg\" alt=\"\" data-id=\"33895\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479181045\" class=\"wp-image-33895\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479181045-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390.jpg\" alt=\"\" data-id=\"33896\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479183390\" class=\"wp-image-33896\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479183390-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707.jpg\" alt=\"\" data-id=\"33897\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479185707\" class=\"wp-image-33897\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479185707-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475.jpg\" alt=\"\" data-id=\"33898\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479189475\" class=\"wp-image-33898\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479189475-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479191624.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479191624.jpg\" alt=\"\" data-id=\"33899\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479191624.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479191624\" class=\"wp-image-33899\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479191624.jpg 720w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479191624-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824.jpg\" alt=\"\" data-id=\"33900\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479194824\" class=\"wp-image-33900\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479194824-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126.jpg\" alt=\"\" data-id=\"33901\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479202126\" class=\"wp-image-33901\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479202126-768x576.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074-1024x768.jpg\" alt=\"\" data-id=\"33902\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479584074\" class=\"wp-image-33902\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479584074.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768-1024x768.jpg\" alt=\"\" data-id=\"33903\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479592768\" class=\"wp-image-33903\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479592768.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133-1024x768.jpg\" alt=\"\" data-id=\"33904\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479601133\" class=\"wp-image-33904\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479601133.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778-1024x768.jpg\" alt=\"\" data-id=\"33905\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479609778\" class=\"wp-image-33905\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479609778.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284-1024x768.jpg\" alt=\"\" data-id=\"33906\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479614284\" class=\"wp-image-33906\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479614284.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449-1024x768.jpg\" alt=\"\" data-id=\"33907\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479617449\" class=\"wp-image-33907\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449-1024x768.jpg 1024w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449-300x225.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449-768x576.jpg 768w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479617449.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"540\" src=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809.jpg\" alt=\"\" data-id=\"33908\" data-full-url=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809.jpg\" data-link=\"https:\/\/pwschool.ac.th\/archives\/33869\/fb_img_1665479236809\" class=\"wp-image-33908\" srcset=\"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809.jpg 960w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809-300x169.jpg 300w, https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809-768x432.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>\u0e23\u0e39\u0e1b\u0e08\u0e32\u0e01\u0e44\u0e25\u0e19\u0e4c\u0e23\u0e39\u0e1b\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21 \u0e42\u0e14\u0e22 \u0e04\u0e38\u0e13\u0e04\u0e23\u0e39\u0e13\u0e31\u0e10\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e0a\u0e34\u0e19\u0e27\u0e07\u0e04\u0e4c \u0e04\u0e38\u0e13\u0e04\u0e23\u0e39\u0e27\u0e23\u0e27\u0e38\u0e12\u0e34 \u0e40\u0e09\u0e35\u0e22\u0e07\u0e01\u0e25\u0e32\u0e07 \u0e04\u0e38\u0e13\u0e04\u0e23\u0e39\u0e0a\u0e34\u0e19\u0e01\u0e23 \u0e28\u0e34\u0e23\u0e34\u0e42\u0e22\u0e18\u0e32 <\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/pwschool.ac.th\/posts\/pfbid0CGKo5YLQc7mBtKgW2JB726KPJvu6Vv7eozQd6YB1Ni5AG3Ti2vhUPzei5vGYGw5sl\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e27\u0e35\u0e14\u0e34\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e27\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e25\u0e39\u0e01\u0e17\u0e38\u0e48\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21<\/a> <\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/pwschool.ac.th\/posts\/pfbid02JCLRSirKY5hJHg4HaFqAfpHrmwicCaB1UXGqQJHy5kMxLVhraFJnzpuRs9UxnNEKl\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e27\u0e35\u0e14\u0e34\u0e42\u0e2d\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e33\u0e21\u0e31\u0e07\u0e04\u0e25\u0e30 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/pwschool.ac.th\/posts\/pfbid07qTpA6qavQ7sB3sFCJjsWvyfigjFbikPxTtTpmfYNkYTcGHqA7AP7HizXh7oqupEl\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e14\u0e1e\u0e34\u0e18\u0e35\u0e40\u0e1b\u0e34\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e27 \u0e13 \u0e17\u0e35\u0e48\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e40\u0e20\u0e2d\u0e1a\u0e32\u0e07\u0e1e\u0e25\u0e35<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/pwschool.ac.th\/posts\/pfbid02P3ScnPYDALDAXzzZHmv1PBVWFs5NCy9GJdv7WsXG468bTjj1HYGp8SbbF4XxDZHdl\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08\u0e27\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35 \u0e40\u0e08\u0e23\u0e34\u0e0d\u0e1e\u0e23<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/PWschoolLibrary\/posts\/pfbid0FXhJJCgiErRXNFmBpeUi5DQhHx1RLo3wsbPBnD5Nu6qWvxrxa3Bd8ZQHALYofhg9l\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e41\u0e1f\u0e19\u0e40\u0e1e\u0e08\u0e2b\u0e49\u0e2d\u0e07\u0e2a\u0e21\u0e38\u0e14\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e39\u0e25\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e27\u0e34\u0e17\u0e22\u0e32\u0e04\u0e21<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e23\u0e31\u0e1a\u0e1a\u0e31\u0e27\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2565\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e0a\u0e32\u0e27\u0e19\u0e32 \u0e2d\u0e1a\u0e15.\u0e1a\u0e32 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":33908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-33869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-6"],"jetpack_featured_media_url":"https:\/\/pwschool.ac.th\/wp-content\/uploads\/2022\/10\/FB_IMG_1665479236809.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/33869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/comments?post=33869"}],"version-history":[{"count":4,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/33869\/revisions"}],"predecessor-version":[{"id":33912,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/posts\/33869\/revisions\/33912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/media\/33908"}],"wp:attachment":[{"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/media?parent=33869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/categories?post=33869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pwschool.ac.th\/home\/wp-json\/wp\/v2\/tags?post=33869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}